{"id":2142,"date":"2024-05-07T09:43:43","date_gmt":"2024-05-07T09:43:43","guid":{"rendered":"https:\/\/www.nominaurea.pt\/noticias\/penhoras-de-vencimento-novos-procedimentos-na-emissao-de-penhora-no-portal-da-autoridade-tributaria\/"},"modified":"2025-10-21T11:48:15","modified_gmt":"2025-10-21T11:48:15","slug":"penhoras-de-vencimento-novos-procedimentos-na-emissao-de-penhora-no-portal-da-autoridade-tributaria","status":"publish","type":"post","link":"https:\/\/www.nominaurea.pt\/es\/noticias\/penhoras-de-vencimento-novos-procedimentos-na-emissao-de-penhora-no-portal-da-autoridade-tributaria\/","title":{"rendered":"Embargos de Sueldos &#8211; Nuevos procedimientos a cumplir en el portal de la Autoridad Tributaria"},"content":{"rendered":"<h5 class=\"bto-encabezamiento\" style=\"text-align: justify;\">Flash Noticias NA 7\/05\/2024<\/h5>\n<h5 style=\"text-align: justify;\">Embargos de Sueldos &#8211; Nuevos procedimientos a cumplir en el portal de la Autoridad Tributaria<\/h5>\n<p style=\"text-align: justify;\">La Autoridad Tributaria y Aduanera de Portugal ha publicado un nuevo procedimiento en su p\u00e1gina web para responder a los procesos de embargo de sueldos, con el objetivo de abordar las limitaciones y dificultades que han sido reportadas por los utilizadores en el portal.<\/p>\n<hr id=\"system-readmore\" \/>\n<p style=\"text-align: justify;\"><a href=\"es\/noticias.html\"><img decoding=\"async\" style=\"float: right; margin-left: 10px;\" src=\"images\/volver.png\" alt=\"\" data-alt=\"Volver\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>\u00bfEn qu\u00e9 consiste?<\/strong><\/p>\n<p style=\"text-align: justify;\">El embargo de un sueldo ocurre como consecuencia de la incapacidad de un empleado para cumplir con una obligaci\u00f3n financiera espec\u00edfica, ya sea hacia una entidad p\u00fablica (Autoridad Tributaria, Seguridad Social, Tribunales y otras agencias estatales) o privada (bancos, empresas de servicios privadas, etc.). Es una forma de cobro coercitivo destinada a reclamar el derecho del acreedor, realizado mediante el embargo judicial de los salarios del empleado.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00bfCu\u00e1les son los deberes del Empleador?<\/strong><\/p>\n<p style=\"text-align: justify;\">Al recibir la notificaci\u00f3n del embargo, el empleador debe responder dentro del per\u00edodo especificado y actuar en consecuencia, deduciendo mensualmente el montante del embargo del salario del empleado, de acuerdo con las reglas establecidas y siempre que las condiciones permitan la deducci\u00f3n. Posteriormente, el empleador debe realizar el pago al deudor (Autoridad Tributaria, Seguridad Social, Tribunal, etc.).<\/p>\n<p style=\"text-align: justify;\"><strong>\u00bfCu\u00e1les son sus l\u00edmites?<\/strong><\/p>\n<p style=\"text-align: justify;\">Seg\u00fan el art\u00edculo 738 del C\u00f3digo de Procedimiento Civil, el embargo de sueldos debe cumplir ciertas reglas:<\/p>\n<p style=\"padding-left: 30px; text-align: justify;\">\u2022 El embargo se aplica en funci\u00f3n del salario neto del empleado, es decir, sus ingresos despu\u00e9s de las deducciones legalmente obligatorias;<\/p>\n<p style=\"padding-left: 30px; text-align: justify;\">\u2022 La parte embargable se especifica en la notificaci\u00f3n, generalmente siendo un tercio o un sexto del salario neto;<\/p>\n<p style=\"padding-left: 30px; text-align: justify;\">\u2022 Al aplicar el embargo, el empleador debe asegurarse de que el empleado reciba al menos el equivalente al salario m\u00ednimo mensual garantizado, 820,00 euros en el a\u00f1o en curso;<\/p>\n<p style=\"padding-left: 30px; text-align: justify;\">\u2022 El montante embargable tiene un l\u00edmite m\u00e1ximo equivalente a tres veces el salario m\u00ednimo garantizado, es decir, 2.460,00 euros en el a\u00f1o en curso [Art\u00edculo 738, CPC, 2013].<\/p>\n<p style=\"text-align: justify;\"><strong>\u00bfC\u00f3mo se calcula?<\/strong><\/p>\n<p style=\"text-align: justify;\">Bas\u00e1ndonos en un salario neto de 1.000,00 euros y cumpliendo con las reglas mencionadas anteriormente, la parte embargable ser\u00eda de 180,00 euros y la parte no embargable ser\u00eda de 820,00 euros. Un tercio del salario neto considerado ser\u00eda de 333,33 euros, sin embargo, esto no garantizar\u00eda el salario m\u00ednimo mensual garantizado. Considerando una parte embargable de 180,00 euros, ya se garantizar\u00eda el salario m\u00ednimo nacional en la fecha actual y el monto restante ser\u00eda embargado.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00bfCu\u00e1les son los nuevos procedimientos para adoptar en la emisi\u00f3n de embargos en el portal de la Autoridad Tributaria?<\/strong><\/p>\n<p style=\"text-align: justify;\">Actualmente para registrar o consultar embargos y emitir gu\u00edas de pago, debe acceder al \u00e1rea de Empresa, seleccionar <strong>\u00abServicios\u00bb<\/strong>, buscar <strong>\u00abRespuesta a solicitudes\u00bb<\/strong> y en el campo <strong>\u00abRespuesta a solicitudes &#8211; Respuesta a solicitudes de embargos, reconocimiento de bienes y respuesta a solicitudes de informaci\u00f3n\u00bb<\/strong>, elegir <strong>\u00abOtros Bienes y Derechos\u00bb<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Verifique los pasos a continuaci\u00f3n<span style=\"caret-color: auto;\">:<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>1.\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<img fetchpriority=\"high\" decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"images\/publicaciones\/2024\/2024.05.07_1.png\" alt=\"\" width=\"848\" height=\"271\" data-alt=\"2024.05.07 1\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>2.<\/strong><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"images\/publicaciones\/2024\/2024.05.07_2.png\" alt=\"2024.05.07 2\" width=\"286\" height=\"450\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>3.<\/strong><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"images\/publicaciones\/2024\/2024.05.07_3.png\" alt=\"2024.05.07 3\" width=\"793\" height=\"567\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>4.<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"images\/publicaciones\/2024\/2024.05.07_4.png\" alt=\"2024.05.07 4\" width=\"644\" height=\"93\" \/><\/p>\n<p style=\"text-align: justify;\">En\u00a0<a href=\"es\/\">Nominaurea<\/a>,\u00a0contamos con equipos especializados para asesorar y ayudarle en la respuesta a las notificaciones de embargos que haya podido recibir de sus colaboradores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Flash Noticias NA 7\/05\/2024 Embargos de Sueldos &#8211; Nuevos procedimientos a cumplir en el portal de la Autoridad Tributaria La Autoridad Tributaria y Aduanera de Portugal ha publicado un nuevo procedimiento en su p\u00e1gina web para responder a los procesos de embargo de sueldos, con el objetivo de abordar las limitaciones y dificultades que han [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-2142","post","type-post","status-publish","format-standard","hentry","category-publicaciones"],"_links":{"self":[{"href":"https:\/\/www.nominaurea.pt\/es\/wp-json\/wp\/v2\/posts\/2142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nominaurea.pt\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nominaurea.pt\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nominaurea.pt\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nominaurea.pt\/es\/wp-json\/wp\/v2\/comments?post=2142"}],"version-history":[{"count":2,"href":"https:\/\/www.nominaurea.pt\/es\/wp-json\/wp\/v2\/posts\/2142\/revisions"}],"predecessor-version":[{"id":2153,"href":"https:\/\/www.nominaurea.pt\/es\/wp-json\/wp\/v2\/posts\/2142\/revisions\/2153"}],"wp:attachment":[{"href":"https:\/\/www.nominaurea.pt\/es\/wp-json\/wp\/v2\/media?parent=2142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nominaurea.pt\/es\/wp-json\/wp\/v2\/categories?post=2142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nominaurea.pt\/es\/wp-json\/wp\/v2\/tags?post=2142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}